{"id":869,"date":"2013-10-18T09:25:07","date_gmt":"2013-10-18T07:25:07","guid":{"rendered":"http:\/\/gereonskeukenthuis.nl\/blog\/?p=869"},"modified":"2016-02-13T10:20:03","modified_gmt":"2016-02-13T09:20:03","slug":"down-to-earth-eten-sacha-boer-jacob-jan-boerma","status":"publish","type":"post","link":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/","title":{"rendered":"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma."},"content":{"rendered":"<h3><\/h3>\n<div><\/div>\n<div id=\"post-body-8307274755587139657\">\n<div dir=\"ltr\">\n<div><a href=\"https:\/\/i0.wp.com\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s1600\/001.JPG\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG?resize=259%2C320\" alt=\"\" width=\"259\" height=\"320\" border=\"0\" \/><\/a><i>\u00a0foto: down to earth<\/i><\/div>\n<p>Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0<b>Down to Earth<\/b>. Het lag gisteren op mijn deurmat. Een mooi kookboek met fotografie en eenvoudige recepten. \u00a0Een samenwerking van fotografe Sacha de Boer en chefkok Jacob-Jan Boerma.<br \/>\nSacha en Jacob Jan gingen de uitdaging aan om een kookboek te maken met gezonde en pure recepten. Recepten, die door iedereen thuis te maken zijn. Sacha probeerde alle recepten uit, fotografeerde ze en liet zich de gerechten goed smaken.<br \/>\nSacha de Boer bekent dat ze voorheen ook gedachteloos wat mee griste uit de supermarkt. Ze had vaak geen tijd om te koken. Na haar afscheid bij het NOS Journaal, werd ze fotografe. Haar bestaan werd nog drukker. En om genoeg energie voor al je creativiteit te hebben, moet je gezond eten. Ik zelf kan daar over meepraten. Je voelt je gewoon beter als je vers en gezond eet. Sacha zette de woorden om in daden.<br \/>\nIn de herfst van \u00a02012 ontmoette Sacha chefkok Jacob-Jan Boerma van restaurant De Leest in Vaassen. Ze wilde enkel foto&#8217;s van haar hand in het restaurant ophangen. Al snel mondde dit idee uit in een volwaardig en gezond kookboek.\u00a0<b>Down to Earth<\/b>\u00a0zat in beider hoofden en ze gingen aan de slag met hun idee\u00ebn. Er werd gekookt, geproefd en gegeten. En natuurlijk prachtig gefotografeerd. Ze kregen er kippenvel van. Van de mooie producten en prachtige gerechten. Met beide benen op de grond en basic.<br \/>\nEn nu ligt het er. hier op mijn eettafel, prachtig vormgegeven. het boek start met\u00a0<b>FRIS<\/b>, gerechten van dagverse producten van het land. Fris gaat over in\u00a0<b>MALS<\/b>, over grillen, het liefst niet in je eentje, maar met vrienden buiten bij het vuur.\u00a0<b>ZILT<\/b>, met smaken uit de zee en van de kwelder.<b>AARDS<\/b>, koken met de groenten van het seizoen. Het boek eindigt met\u00a0<b>ZOET<\/b>, hoe kan het ook anders. Honingzoet met een pleidooi voor bijen.<br \/>\nIk krijg gewoon trek van de mooie recepten en vormgeving. De foto&#8217;s in het boek zijn prachtig en dagen je uit. Ze sporen aan om de recepten te proberen. Ik ga er in ieder geval veel inspiratie uit op doen voor mijn blogs. De technieken worden goed uitgelegd en er is een sectie met basisrecepten.<br \/>\nEen aanrader vind ik\u00a0<b>Down to Earth<\/b>. Ik sta nu al te popelen om de kiprolletjes met katenspek en bloemkool-preistamppot te maken.<\/p>\n<div><a href=\"https:\/\/i0.wp.com\/2.bp.blogspot.com\/-GkRmthM6PHE\/UmDhTALibQI\/AAAAAAAABK4\/Aw3To5C8VR4\/s1600\/003.JPG\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/2.bp.blogspot.com\/-GkRmthM6PHE\/UmDhTALibQI\/AAAAAAAABK4\/Aw3To5C8VR4\/s320\/003.JPG?resize=320%2C216\" alt=\"\" width=\"320\" height=\"216\" border=\"0\" \/><\/a>\u00a0<i>foto: kiprolletje<\/i>s<\/div>\n<p>Het boek\u00a0<b>Down to Earth<\/b>\u00a0(ISBN 9789000332816) is een uitgave van\u00a0<a href=\"http:\/\/www.unieboekspectrum.nl\/\">www.unieboekspectrum.nl<\/a>\u00a0en ligt voor 25 Euro in de boekhandels.<\/p>\n<p>Kijk voor meer inspiratie ook eens op\u00a0<a href=\"http:\/\/www.sachadeboer.nl\/\">www.sachadeboer.nl<\/a>\u00a0of prik eens een vorkje bij\u00a0<a href=\"http:\/\/www.restaurantdeleest.nl\/\">www.restaurantdeleest.nl<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0foto: down to earth Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat. Een mooi kookboek met fotografie en eenvoudige recepten. \u00a0Een samenwerking van fotografe Sacha de Boer en chefkok Jacob-Jan Boerma. Sacha en Jacob Jan gingen de uitdaging aan om een kookboek te &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/\" class=\"more-link\">Lees verder <span class=\"screen-reader-text\">&#8220;Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma.&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[23,1,12,24,30,7],"tags":[],"class_list":["post-869","post","type-post","status-publish","format-standard","hentry","category-creatief","category-geen-categorie","category-gesprekken-en-gerechten","category-kunst","category-reviews","category-soulfood"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma. - Gereons Keuken Thuis<\/title>\n<meta name=\"description\" content=\"Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma. - Gereons Keuken Thuis\" \/>\n<meta property=\"og:description\" content=\"Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/\" \/>\n<meta property=\"og:site_name\" content=\"Gereons Keuken Thuis\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/gereon.deleeuw\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-18T07:25:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-13T09:20:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG\" \/>\n<meta name=\"author\" content=\"gereon de leeuw\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gereon_DL\" \/>\n<meta name=\"twitter:site\" content=\"@gereon_DL\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"gereon de leeuw\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/\"},\"author\":{\"name\":\"gereon de leeuw\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#\\\/schema\\\/person\\\/1951fe17bd83814423b907d4bb64fae3\"},\"headline\":\"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma.\",\"datePublished\":\"2013-10-18T07:25:07+00:00\",\"dateModified\":\"2016-02-13T09:20:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/\"},\"wordCount\":453,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-MW8o35P7gTw\\\/UmDheoWtjeI\\\/AAAAAAAABLA\\\/y9jeBZRALqA\\\/s320\\\/001.JPG\",\"articleSection\":[\"creatief\",\"Geen categorie\",\"Gesprekken en Gerechten\",\"kunst\",\"reviews\",\"Soulfood\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/\",\"url\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/\",\"name\":\"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma. - Gereons Keuken Thuis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-MW8o35P7gTw\\\/UmDheoWtjeI\\\/AAAAAAAABLA\\\/y9jeBZRALqA\\\/s320\\\/001.JPG\",\"datePublished\":\"2013-10-18T07:25:07+00:00\",\"dateModified\":\"2016-02-13T09:20:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#\\\/schema\\\/person\\\/1951fe17bd83814423b907d4bb64fae3\"},\"description\":\"Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#primaryimage\",\"url\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-MW8o35P7gTw\\\/UmDheoWtjeI\\\/AAAAAAAABLA\\\/y9jeBZRALqA\\\/s320\\\/001.JPG\",\"contentUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-MW8o35P7gTw\\\/UmDheoWtjeI\\\/AAAAAAAABLA\\\/y9jeBZRALqA\\\/s320\\\/001.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/\",\"name\":\"Gereons Keuken Thuis\",\"description\":\"Fijne verhalen over wijn en spijs voor alledag.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#\\\/schema\\\/person\\\/1951fe17bd83814423b907d4bb64fae3\",\"name\":\"gereon de leeuw\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/beb7b5ff670f0591c872d4b4776e22422e92d7afcb72e1e1f19c58fb5657f5fe?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/beb7b5ff670f0591c872d4b4776e22422e92d7afcb72e1e1f19c58fb5657f5fe?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/beb7b5ff670f0591c872d4b4776e22422e92d7afcb72e1e1f19c58fb5657f5fe?s=96&r=g\",\"caption\":\"gereon de leeuw\"},\"sameAs\":[\"http:\\\/\\\/gereonskeukenthuis.nl\"],\"url\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/author\\\/gereon-de-leeuw\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma. - Gereons Keuken Thuis","description":"Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/","og_locale":"nl_NL","og_type":"article","og_title":"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma. - Gereons Keuken Thuis","og_description":"Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat.\u00a0","og_url":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/","og_site_name":"Gereons Keuken Thuis","article_publisher":"http:\/\/www.facebook.com\/gereon.deleeuw","article_published_time":"2013-10-18T07:25:07+00:00","article_modified_time":"2016-02-13T09:20:03+00:00","og_image":[{"url":"http:\/\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG","type":"","width":"","height":""}],"author":"gereon de leeuw","twitter_card":"summary_large_image","twitter_creator":"@gereon_DL","twitter_site":"@gereon_DL","twitter_misc":{"Geschreven door":"gereon de leeuw","Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#article","isPartOf":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/"},"author":{"name":"gereon de leeuw","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#\/schema\/person\/1951fe17bd83814423b907d4bb64fae3"},"headline":"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma.","datePublished":"2013-10-18T07:25:07+00:00","dateModified":"2016-02-13T09:20:03+00:00","mainEntityOfPage":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/"},"wordCount":453,"commentCount":0,"image":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG","articleSection":["creatief","Geen categorie","Gesprekken en Gerechten","kunst","reviews","Soulfood"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/","url":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/","name":"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma. - Gereons Keuken Thuis","isPartOf":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#primaryimage"},"image":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG","datePublished":"2013-10-18T07:25:07+00:00","dateModified":"2016-02-13T09:20:03+00:00","author":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#\/schema\/person\/1951fe17bd83814423b907d4bb64fae3"},"description":"Fris, mals, zilt, aards en zoet staat er op de cover van\u00a0Down to Earth. Het lag gisteren op mijn deurmat.\u00a0","breadcrumb":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#primaryimage","url":"http:\/\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG","contentUrl":"http:\/\/1.bp.blogspot.com\/-MW8o35P7gTw\/UmDheoWtjeI\/AAAAAAAABLA\/y9jeBZRALqA\/s320\/001.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/down-to-earth-eten-sacha-boer-jacob-jan-boerma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gereonskeukenthuis.nl\/blog\/"},{"@type":"ListItem","position":2,"name":"Down to Earth, eten met Sacha de Boer en Jacob-Jan Boerma."}]},{"@type":"WebSite","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#website","url":"https:\/\/gereonskeukenthuis.nl\/blog\/","name":"Gereons Keuken Thuis","description":"Fijne verhalen over wijn en spijs voor alledag.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gereonskeukenthuis.nl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#\/schema\/person\/1951fe17bd83814423b907d4bb64fae3","name":"gereon de leeuw","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/beb7b5ff670f0591c872d4b4776e22422e92d7afcb72e1e1f19c58fb5657f5fe?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/beb7b5ff670f0591c872d4b4776e22422e92d7afcb72e1e1f19c58fb5657f5fe?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/beb7b5ff670f0591c872d4b4776e22422e92d7afcb72e1e1f19c58fb5657f5fe?s=96&r=g","caption":"gereon de leeuw"},"sameAs":["http:\/\/gereonskeukenthuis.nl"],"url":"https:\/\/gereonskeukenthuis.nl\/blog\/author\/gereon-de-leeuw\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p39CAa-e1","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/posts\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":3,"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"predecessor-version":[{"id":2396,"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/posts\/869\/revisions\/2396"}],"wp:attachment":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}