{"id":82,"count":95,"description":"","link":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/","name":"wereldkeuken","slug":"wereldkeuken","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>wereldkeuken Archives - Gereons Keuken Thuis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wereldkeuken Archives - Gereons Keuken Thuis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/\" \/>\n<meta property=\"og:site_name\" content=\"Gereons Keuken Thuis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gereon_DL\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/category\\\/wereldkeuken\\\/\",\"url\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/category\\\/wereldkeuken\\\/\",\"name\":\"wereldkeuken Archives - Gereons Keuken Thuis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/category\\\/wereldkeuken\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/category\\\/wereldkeuken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"wereldkeuken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/\",\"name\":\"Gereons Keuken Thuis\",\"description\":\"Fijne verhalen over wijn en spijs voor alledag.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gereonskeukenthuis.nl\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"wereldkeuken Archives - Gereons Keuken Thuis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/","og_locale":"nl_NL","og_type":"article","og_title":"wereldkeuken Archives - Gereons Keuken Thuis","og_url":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/","og_site_name":"Gereons Keuken Thuis","twitter_card":"summary_large_image","twitter_site":"@gereon_DL","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/","url":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/","name":"wereldkeuken Archives - Gereons Keuken Thuis","isPartOf":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/category\/wereldkeuken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gereonskeukenthuis.nl\/blog\/"},{"@type":"ListItem","position":2,"name":"wereldkeuken"}]},{"@type":"WebSite","@id":"https:\/\/gereonskeukenthuis.nl\/blog\/#website","url":"https:\/\/gereonskeukenthuis.nl\/blog\/","name":"Gereons Keuken Thuis","description":"Fijne verhalen over wijn en spijs voor alledag.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gereonskeukenthuis.nl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/categories\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gereonskeukenthuis.nl\/blog\/wp-json\/wp\/v2\/posts?categories=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}